{"id":1008697,"date":"2022-08-24T16:53:13","date_gmt":"2022-08-24T22:53:13","guid":{"rendered":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/"},"modified":"2024-08-27T12:56:33","modified_gmt":"2024-08-27T18:56:33","slug":"pechuga-con-ala","status":"publish","type":"product","link":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/","title":{"rendered":"Pechuga con Ala"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1008645,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"product_cat":[78,71],"product_tag":[],"class_list":["post-1008697","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-congelados","product_cat-todos","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pechuga con Ala - Tip Top<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pechuga con Ala - Tip Top\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/\" \/>\n<meta property=\"og:site_name\" content=\"Tip Top\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-27T18:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tanbuenoquesenota.com\/ni\/wp-content\/uploads\/sites\/5\/2022\/08\/Pechuga-con-ala.png\" \/>\n\t<meta property=\"og:image:width\" content=\"645\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/\",\"url\":\"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/\",\"name\":\"Pechuga con Ala - Tip Top\",\"isPartOf\":{\"@id\":\"https:\/\/tanbuenoquesenota.com\/ni\/#website\"},\"datePublished\":\"2022-08-24T22:53:13+00:00\",\"dateModified\":\"2024-08-27T18:56:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tanbuenoquesenota.com\/ni\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/tanbuenoquesenota.com\/ni\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pechuga con Ala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tanbuenoquesenota.com\/ni\/#website\",\"url\":\"https:\/\/tanbuenoquesenota.com\/ni\/\",\"name\":\"Tip Top\",\"description\":\"Garantizamos la frescura en todas nuestras presentaciones.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tanbuenoquesenota.com\/ni\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pechuga con Ala - Tip Top","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/","og_locale":"es_ES","og_type":"article","og_title":"Pechuga con Ala - Tip Top","og_url":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/","og_site_name":"Tip Top","article_modified_time":"2024-08-27T18:56:33+00:00","og_image":[{"width":645,"height":624,"url":"https:\/\/tanbuenoquesenota.com\/ni\/wp-content\/uploads\/sites\/5\/2022\/08\/Pechuga-con-ala.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/","url":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/","name":"Pechuga con Ala - Tip Top","isPartOf":{"@id":"https:\/\/tanbuenoquesenota.com\/ni\/#website"},"datePublished":"2022-08-24T22:53:13+00:00","dateModified":"2024-08-27T18:56:33+00:00","breadcrumb":{"@id":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tanbuenoquesenota.com\/ni\/product\/pechuga-con-ala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tanbuenoquesenota.com\/ni\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/tanbuenoquesenota.com\/ni\/shop\/"},{"@type":"ListItem","position":3,"name":"Pechuga con Ala"}]},{"@type":"WebSite","@id":"https:\/\/tanbuenoquesenota.com\/ni\/#website","url":"https:\/\/tanbuenoquesenota.com\/ni\/","name":"Tip Top","description":"Garantizamos la frescura en todas nuestras presentaciones.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tanbuenoquesenota.com\/ni\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/product\/1008697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/comments?post=1008697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/media\/1008645"}],"wp:attachment":[{"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/media?parent=1008697"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/product_cat?post=1008697"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tanbuenoquesenota.com\/ni\/wp-json\/wp\/v2\/product_tag?post=1008697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}